{"id":68412,"date":"2019-10-22T15:50:31","date_gmt":"2019-10-22T14:50:31","guid":{"rendered":"https:\/\/www.wanarun.net\/blog\/?p=68412"},"modified":"2019-10-22T15:50:32","modified_gmt":"2019-10-22T14:50:32","slug":"adidas-terrex-agravic-flow","status":"publish","type":"post","link":"https:\/\/www.wanarun.net\/blog\/adidas-terrex-agravic-flow-68412.html","title":{"rendered":"adidas Terrex Agravic Flow tests et avis"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2019\/10\/adidas-terrex-agravic-flow-1.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2019\/10\/adidas-terrex-agravic-flow-1-1024x768.jpg\" alt=\"adidas Terrex Agravic Flow \" class=\"wp-image-68421\" srcset=\"https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2019\/10\/adidas-terrex-agravic-flow-1-1024x768.jpg 1024w, https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2019\/10\/adidas-terrex-agravic-flow-1-300x225.jpg 300w, https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2019\/10\/adidas-terrex-agravic-flow-1-768x576.jpg 768w, https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2019\/10\/adidas-terrex-agravic-flow-1-150x113.jpg 150w, https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2019\/10\/adidas-terrex-agravic-flow-1-620x465.jpg 620w, https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2019\/10\/adidas-terrex-agravic-flow-1.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p>Quand on teste un mod\u00e8le trail de la marque adidas, on ne peut pas oublier les pr\u00e9c\u00e9dents. Si vous couriez d\u00e9j\u00e0 sur les chemins il y a quelques ann\u00e9es, vous aviez sans aucun doute entendu parl\u00e9 de la Supernova Riot. C&rsquo;\u00e9tait l&rsquo;une des meilleures chaussures de trail au d\u00e9but des ann\u00e9es 2010. Elle a re\u00e7u de nombreux prix en France et \u00e0 l&rsquo;\u00e9tranger. <\/p>\n\n\n\n<p>Jusqu&rsquo;au jour o\u00f9 les \u00e9quipes d&rsquo;adidas ont compl\u00e8tement transform\u00e9 ce mod\u00e8le. Les supernova Riot devenant des chaussures montantes avec un syst\u00e8me de la\u00e7age et une sorte de rabat en mesh qui pourrait faire office de gu\u00eatre. Si certains s&rsquo;accordaient pour dire qu&rsquo;elles avaient un look diff\u00e9rent, les traileurs n&rsquo;ont pas retrouv\u00e9 leurs habitudes et les points forts de ce mod\u00e8le. Le la\u00e7age et la pression exerc\u00e9 sur le coup de pied posaient probl\u00e8me&#8230; En une mise \u00e0 jour, les traileurs ont abandonn\u00e9 le mod\u00e8le&#8230; L&rsquo;histoire de la Supernova Riot est devenue un cas d&rsquo;\u00e9cole sur le choix d&rsquo;am\u00e9liorations des chaussures de course \u00e0 pied.<\/p>\n\n\n\n<p>Depuis cette histoire, la Supernova Riot a totalement disparu. Forc\u00e9ment \u00e0 chaque test de la marque, on essaye de retrouver les qualit\u00e9s de cet illustre mod\u00e8le.<\/p>\n\n\n\n<p>En s\u00e9parant les mod\u00e8les route et les mod\u00e8les trail et en incluant la gamme trail dans la famille Terrex, adidas offre une meilleure compr\u00e9hension de ses diff\u00e9rents produits. Si la gamme Terrex g\u00e8re le sport outdoor, vous pouvez y trouver des mod\u00e8les de randonnn\u00e9e aussi bien que des mod\u00e8les de trail.<\/p>\n\n\n\n<p>C&rsquo;est somme toute assez logique, il y a surement plus de point commun entre une chaussure de trail et de randonn\u00e9e qu&rsquo;entre une chaussure de running et une chaussure de trail. <\/p>\n\n\n\n<p>Mais revenons \u00e0 ce mod\u00e8le sp\u00e9cifique l&rsquo;adidas Terrex Agravic Flow. Pour moi, cette chaussure poss\u00e8de tous les \u00e9l\u00e9ments d&rsquo;une bonne chaussure de trail qui passe partout.<\/p>\n\n\n\n<p>Elle est relativement l\u00e9g\u00e8re avec un poids de 330 grammes en 43 1\/3. Elle poss\u00e8de une semelle Continentale compl\u00e8te qui assure une excellente adh\u00e9rence et une bonne durabilit\u00e9. Le confort d&rsquo;accueil avec un mesh doubl\u00e9 et un rembourrage sur le talon. Elle est compos\u00e9e d&rsquo;une partie de semelle interm\u00e9diaire en Boost pour assurer un bon amorti.  <\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2019\/10\/adidas-terrex-agravic-flow-semelle.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2019\/10\/adidas-terrex-agravic-flow-semelle-1024x768.jpg\" alt=\"adidas Terrex Agravic Flow semelle\" class=\"wp-image-68422\" srcset=\"https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2019\/10\/adidas-terrex-agravic-flow-semelle-1024x768.jpg 1024w, https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2019\/10\/adidas-terrex-agravic-flow-semelle-300x225.jpg 300w, https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2019\/10\/adidas-terrex-agravic-flow-semelle-768x576.jpg 768w, https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2019\/10\/adidas-terrex-agravic-flow-semelle-150x113.jpg 150w, https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2019\/10\/adidas-terrex-agravic-flow-semelle-620x465.jpg 620w, https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2019\/10\/adidas-terrex-agravic-flow-semelle.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p>Solide, elle passe partout. Sur les parties de transitions sur route, elle n&rsquo;est pas raide. Sur les graviers, elle offre une bonne accroche avec sa semelle d&rsquo;usure rugueuse. Dans la boue, elle passe tr\u00e8s bien avec les gros crampons.<\/p>\n\n\n\n<p>Je suis pass\u00e9 sur la plupart des terrains avec ce mod\u00e8le : graviers, boue, glaise, chemins blancs&#8230; avec plus ou moins de pentes. Jusqu&rsquo;\u00e0 un dernier trail de nuit tr\u00e8s r\u00e9cemment o\u00f9 les conditions m\u00e9t\u00e9orologiques des jours pr\u00e9c\u00e9dents ont donn\u00e9 un terrain plut\u00f4t compliqu\u00e9. Je ne lui trouve que des qualit\u00e9s. <\/p>\n\n\n\n<p>J&rsquo;ai toujours un peu de mal en changeant de chaussure de trail car il faut reprendre ses rep\u00e8res, retrouver confiance pour savoir ce qu&rsquo;on peut faire ou ne pas faire. <\/p>\n\n\n\n<p>J&rsquo;ai besoin de cette confiance pour savoir si je peux me l\u00e2cher dans une descente ou si je peux poser mon pied dans un d\u00e9vers sans risquer de glisser ou de prendre un mauvais appui. <\/p>\n\n\n\n<p>Par rapport aux premiers mod\u00e8les Agravic, quelques changements sont notables, il y a plus de mousses Boost sous le talon. La languette est maintenant en mesh identique et compl\u00e8tement cousue au chaussant. Et alors qu&rsquo;adidas avait la r\u00e9putation de faire des mod\u00e8les assez fins en largeur, je trouve qu&rsquo;il y a un peu plus d&rsquo;espace et devrait satisfaire les coureurs ayant un pied un peu plus large qu&rsquo;\u00e0 l&rsquo;accoutum\u00e9.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2019\/10\/adidas-terrex-agravic-flow-2.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2019\/10\/adidas-terrex-agravic-flow-2-1024x768.jpg\" alt=\"adidas Terrex Agravic Flow \" class=\"wp-image-68423\" srcset=\"https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2019\/10\/adidas-terrex-agravic-flow-2-1024x768.jpg 1024w, https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2019\/10\/adidas-terrex-agravic-flow-2-300x225.jpg 300w, https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2019\/10\/adidas-terrex-agravic-flow-2-768x576.jpg 768w, https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2019\/10\/adidas-terrex-agravic-flow-2-150x113.jpg 150w, https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2019\/10\/adidas-terrex-agravic-flow-2-620x465.jpg 620w, https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2019\/10\/adidas-terrex-agravic-flow-2.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p>Je trouve que le mod\u00e8le \u00e9volue dans le bon sens et propose un excellent rapport qualit\u00e9 \/ prix puisqu&rsquo;il est disponible en prix public \u00e0 140 euros et  vous pouvez l&rsquo;acheter moins cher en p\u00e9riode de promotion ou si vous profitez d&rsquo;un code promo.<\/p>\n\n\n\n<p>Le mod\u00e8le <a href=\"https:\/\/www.i-run.fr\/chaussures_homme\/Trail_c15\/adidas_m10\/adidas-Terrex-Agravic-Flow-M_adidas_fiche_89070.html\">adidas Terrex Agravic<\/a> Flow test\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<a href=\"https:\/\/www.wanarun.net\/blog\/adidas-terrex-agravic-flow-68412.html\"><img width=\"150\" height=\"150\" src=\"https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2019\/10\/adidas-terrex-agravic-flow-1-150x150.jpg\" class=\"alignleft tfe wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2019\/10\/adidas-terrex-agravic-flow-1-150x150.jpg 150w, https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2019\/10\/adidas-terrex-agravic-flow-1-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><p>Quand on teste un mod\u00e8le trail de la marque adidas, on ne peut pas oublier les pr\u00e9c\u00e9dents. Si vous couriez d\u00e9j\u00e0 sur les chemins il y a quelques ann\u00e9es, vous aviez sans aucun doute entendu parl\u00e9 de la Supernova Riot. C&rsquo;\u00e9tait l&rsquo;une des meilleures chaussures de trail au d\u00e9but des ann\u00e9es 2010. Elle a re\u00e7u [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":68421,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[12501,9,12503],"tags":[26],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>adidas Terrex Agravic Flow tests et avis<\/title>\n<meta name=\"description\" content=\"Quand on teste un mod\u00e8le trail de la marque adidas, on ne peut pas oublier les pr\u00e9c\u00e9dents. Si vous couriez d\u00e9j\u00e0 sur les chemins il y a quelques ann\u00e9es,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wanarun.net\/blog\/adidas-terrex-agravic-flow-68412.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"adidas Terrex Agravic Flow tests et avis\" \/>\n<meta property=\"og:description\" content=\"Quand on teste un mod\u00e8le trail de la marque adidas, on ne peut pas oublier les pr\u00e9c\u00e9dents. Si vous couriez d\u00e9j\u00e0 sur les chemins il y a quelques ann\u00e9es,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wanarun.net\/blog\/adidas-terrex-agravic-flow-68412.html\" \/>\n<meta property=\"og:site_name\" content=\"Wanarun, le blog du running, du trail et de la course \u00e0 pied\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wanarun\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-22T14:50:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-22T14:50:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2019\/10\/adidas-terrex-agravic-flow-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Manu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.wanarun.net\/blog\/#organization\",\"name\":\"Wanarun\",\"url\":\"https:\/\/www.wanarun.net\/blog\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/wanarunnet\/\",\"https:\/\/www.youtube.com\/user\/wanarunnet\",\"https:\/\/www.facebook.com\/wanarun\/\",\"https:\/\/twitter.com\/wanarun\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.wanarun.net\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2018\/03\/logo-wanarun.jpg\",\"contentUrl\":\"https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2018\/03\/logo-wanarun.jpg\",\"width\":1196,\"height\":1082,\"caption\":\"Wanarun\"},\"image\":{\"@id\":\"https:\/\/www.wanarun.net\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.wanarun.net\/blog\/#website\",\"url\":\"https:\/\/www.wanarun.net\/blog\/\",\"name\":\"Wanarun, le blog du running, du trail et de la course \u00e0 pied\",\"description\":\"Informations, remarques, avis, conseils sur la course \u00e0 pied.\",\"publisher\":{\"@id\":\"https:\/\/www.wanarun.net\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.wanarun.net\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.wanarun.net\/blog\/adidas-terrex-agravic-flow-68412.html#primaryimage\",\"url\":\"https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2019\/10\/adidas-terrex-agravic-flow-1.jpg\",\"contentUrl\":\"https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2019\/10\/adidas-terrex-agravic-flow-1.jpg\",\"width\":1200,\"height\":900},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.wanarun.net\/blog\/adidas-terrex-agravic-flow-68412.html#webpage\",\"url\":\"https:\/\/www.wanarun.net\/blog\/adidas-terrex-agravic-flow-68412.html\",\"name\":\"adidas Terrex Agravic Flow tests et avis\",\"isPartOf\":{\"@id\":\"https:\/\/www.wanarun.net\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.wanarun.net\/blog\/adidas-terrex-agravic-flow-68412.html#primaryimage\"},\"datePublished\":\"2019-10-22T14:50:31+00:00\",\"dateModified\":\"2019-10-22T14:50:32+00:00\",\"description\":\"Quand on teste un mod\u00e8le trail de la marque adidas, on ne peut pas oublier les pr\u00e9c\u00e9dents. Si vous couriez d\u00e9j\u00e0 sur les chemins il y a quelques ann\u00e9es,\",\"breadcrumb\":{\"@id\":\"https:\/\/www.wanarun.net\/blog\/adidas-terrex-agravic-flow-68412.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.wanarun.net\/blog\/adidas-terrex-agravic-flow-68412.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.wanarun.net\/blog\/adidas-terrex-agravic-flow-68412.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"adidas Terrex Agravic Flow tests et avis\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/www.wanarun.net\/blog\/adidas-terrex-agravic-flow-68412.html#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.wanarun.net\/blog\/adidas-terrex-agravic-flow-68412.html#webpage\"},\"author\":{\"@id\":\"https:\/\/www.wanarun.net\/blog\/#\/schema\/person\/bfb3bc166306771639fdc2bc6ac79771\"},\"headline\":\"adidas Terrex Agravic Flow tests et avis\",\"datePublished\":\"2019-10-22T14:50:31+00:00\",\"dateModified\":\"2019-10-22T14:50:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.wanarun.net\/blog\/adidas-terrex-agravic-flow-68412.html#webpage\"},\"wordCount\":692,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.wanarun.net\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.wanarun.net\/blog\/adidas-terrex-agravic-flow-68412.html#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2019\/10\/adidas-terrex-agravic-flow-1.jpg\",\"keywords\":[\"adidas\"],\"articleSection\":[\"Chaussures\",\"Tests\",\"Trail\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.wanarun.net\/blog\/adidas-terrex-agravic-flow-68412.html#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.wanarun.net\/blog\/#\/schema\/person\/bfb3bc166306771639fdc2bc6ac79771\",\"name\":\"Manu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.wanarun.net\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/717b7c28298e2900c61bceb611a4918a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/717b7c28298e2900c61bceb611a4918a?s=96&d=mm&r=g\",\"caption\":\"Manu\"},\"sameAs\":[\"https:\/\/www.wanarun.net\"],\"url\":\"https:\/\/www.wanarun.net\/blog\/author\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"adidas Terrex Agravic Flow tests et avis","description":"Quand on teste un mod\u00e8le trail de la marque adidas, on ne peut pas oublier les pr\u00e9c\u00e9dents. Si vous couriez d\u00e9j\u00e0 sur les chemins il y a quelques ann\u00e9es,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wanarun.net\/blog\/adidas-terrex-agravic-flow-68412.html","og_locale":"fr_FR","og_type":"article","og_title":"adidas Terrex Agravic Flow tests et avis","og_description":"Quand on teste un mod\u00e8le trail de la marque adidas, on ne peut pas oublier les pr\u00e9c\u00e9dents. Si vous couriez d\u00e9j\u00e0 sur les chemins il y a quelques ann\u00e9es,","og_url":"https:\/\/www.wanarun.net\/blog\/adidas-terrex-agravic-flow-68412.html","og_site_name":"Wanarun, le blog du running, du trail et de la course \u00e0 pied","article_publisher":"https:\/\/www.facebook.com\/wanarun\/","article_published_time":"2019-10-22T14:50:31+00:00","article_modified_time":"2019-10-22T14:50:32+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2019\/10\/adidas-terrex-agravic-flow-1.jpg","type":"image\/jpeg"}],"twitter_misc":{"\u00c9crit par":"Manu","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/www.wanarun.net\/blog\/#organization","name":"Wanarun","url":"https:\/\/www.wanarun.net\/blog\/","sameAs":["https:\/\/www.instagram.com\/wanarunnet\/","https:\/\/www.youtube.com\/user\/wanarunnet","https:\/\/www.facebook.com\/wanarun\/","https:\/\/twitter.com\/wanarun"],"logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.wanarun.net\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2018\/03\/logo-wanarun.jpg","contentUrl":"https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2018\/03\/logo-wanarun.jpg","width":1196,"height":1082,"caption":"Wanarun"},"image":{"@id":"https:\/\/www.wanarun.net\/blog\/#\/schema\/logo\/image\/"}},{"@type":"WebSite","@id":"https:\/\/www.wanarun.net\/blog\/#website","url":"https:\/\/www.wanarun.net\/blog\/","name":"Wanarun, le blog du running, du trail et de la course \u00e0 pied","description":"Informations, remarques, avis, conseils sur la course \u00e0 pied.","publisher":{"@id":"https:\/\/www.wanarun.net\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wanarun.net\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.wanarun.net\/blog\/adidas-terrex-agravic-flow-68412.html#primaryimage","url":"https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2019\/10\/adidas-terrex-agravic-flow-1.jpg","contentUrl":"https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2019\/10\/adidas-terrex-agravic-flow-1.jpg","width":1200,"height":900},{"@type":"WebPage","@id":"https:\/\/www.wanarun.net\/blog\/adidas-terrex-agravic-flow-68412.html#webpage","url":"https:\/\/www.wanarun.net\/blog\/adidas-terrex-agravic-flow-68412.html","name":"adidas Terrex Agravic Flow tests et avis","isPartOf":{"@id":"https:\/\/www.wanarun.net\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.wanarun.net\/blog\/adidas-terrex-agravic-flow-68412.html#primaryimage"},"datePublished":"2019-10-22T14:50:31+00:00","dateModified":"2019-10-22T14:50:32+00:00","description":"Quand on teste un mod\u00e8le trail de la marque adidas, on ne peut pas oublier les pr\u00e9c\u00e9dents. Si vous couriez d\u00e9j\u00e0 sur les chemins il y a quelques ann\u00e9es,","breadcrumb":{"@id":"https:\/\/www.wanarun.net\/blog\/adidas-terrex-agravic-flow-68412.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wanarun.net\/blog\/adidas-terrex-agravic-flow-68412.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.wanarun.net\/blog\/adidas-terrex-agravic-flow-68412.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"adidas Terrex Agravic Flow tests et avis"}]},{"@type":"Article","@id":"https:\/\/www.wanarun.net\/blog\/adidas-terrex-agravic-flow-68412.html#article","isPartOf":{"@id":"https:\/\/www.wanarun.net\/blog\/adidas-terrex-agravic-flow-68412.html#webpage"},"author":{"@id":"https:\/\/www.wanarun.net\/blog\/#\/schema\/person\/bfb3bc166306771639fdc2bc6ac79771"},"headline":"adidas Terrex Agravic Flow tests et avis","datePublished":"2019-10-22T14:50:31+00:00","dateModified":"2019-10-22T14:50:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.wanarun.net\/blog\/adidas-terrex-agravic-flow-68412.html#webpage"},"wordCount":692,"commentCount":0,"publisher":{"@id":"https:\/\/www.wanarun.net\/blog\/#organization"},"image":{"@id":"https:\/\/www.wanarun.net\/blog\/adidas-terrex-agravic-flow-68412.html#primaryimage"},"thumbnailUrl":"https:\/\/www.wanarun.net\/blog\/wp-content\/uploads\/2019\/10\/adidas-terrex-agravic-flow-1.jpg","keywords":["adidas"],"articleSection":["Chaussures","Tests","Trail"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.wanarun.net\/blog\/adidas-terrex-agravic-flow-68412.html#respond"]}]},{"@type":"Person","@id":"https:\/\/www.wanarun.net\/blog\/#\/schema\/person\/bfb3bc166306771639fdc2bc6ac79771","name":"Manu","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.wanarun.net\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/717b7c28298e2900c61bceb611a4918a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/717b7c28298e2900c61bceb611a4918a?s=96&d=mm&r=g","caption":"Manu"},"sameAs":["https:\/\/www.wanarun.net"],"url":"https:\/\/www.wanarun.net\/blog\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/www.wanarun.net\/blog\/wp-json\/wp\/v2\/posts\/68412"}],"collection":[{"href":"https:\/\/www.wanarun.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wanarun.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wanarun.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wanarun.net\/blog\/wp-json\/wp\/v2\/comments?post=68412"}],"version-history":[{"count":3,"href":"https:\/\/www.wanarun.net\/blog\/wp-json\/wp\/v2\/posts\/68412\/revisions"}],"predecessor-version":[{"id":68425,"href":"https:\/\/www.wanarun.net\/blog\/wp-json\/wp\/v2\/posts\/68412\/revisions\/68425"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wanarun.net\/blog\/wp-json\/wp\/v2\/media\/68421"}],"wp:attachment":[{"href":"https:\/\/www.wanarun.net\/blog\/wp-json\/wp\/v2\/media?parent=68412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wanarun.net\/blog\/wp-json\/wp\/v2\/categories?post=68412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wanarun.net\/blog\/wp-json\/wp\/v2\/tags?post=68412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}